{"id":1,"count":1,"description":"","link":"https:\/\/bayancela.com\/digitalizate\/index.php\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/bayancela.com\/digitalizate\/index.php\/wp-json\/wp\/v2\/categories\/1"}],"collection":[{"href":"https:\/\/bayancela.com\/digitalizate\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/bayancela.com\/digitalizate\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/bayancela.com\/digitalizate\/index.php\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}